{"id":1404,"date":"2024-11-20T17:28:40","date_gmt":"2024-11-20T09:28:40","guid":{"rendered":"https:\/\/www.tai-marketing.com\/?post_type=product&#038;p=1404"},"modified":"2024-11-20T17:28:40","modified_gmt":"2024-11-20T09:28:40","slug":"wireless-ergonomic-keyboard","status":"publish","type":"product","link":"https:\/\/www.tai-marketing.com\/index.php\/product\/wireless-ergonomic-keyboard\/","title":{"rendered":"Logitech \u7f85\u6280 Ergo K860 \u7121\u7dda\u4eba\u9ad4\u5de5\u5b78\u9375\u76e4"},"content":{"rendered":"<ul class=\"a-unordered-list a-vertical a-spacing-mini\">\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u7121\u7dda\u7bc4\u570d:10 \u516c\u5c3a (33 \u82f1\u5c3a) \u7121\u7dda\u7bc4\u570d<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u6539\u5584\u6253\u5b57\u59ff\u52e2:\u4f7f\u7528\u5f4e\u66f2\u3001\u5206\u5272\u7684\u95dc\u9375\u6846\u67b6\u66f4\u81ea\u7136\u5730\u6253\u5b57,\u501f\u52a9\u50be\u659c\u7684\u9375\u76e4\u8a2d\u8a08,\u6e1b\u5c11\u624b\u8155\u548c\u524d\u81c2\u7684\u808c\u8089\u75b2\u52de\u3002<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u6795\u982d\u8b77\u8155:\u5f27\u5f62\u8155\u588a\u9644\u8a18\u61b6\u6ce1\u68c9\u5c64,\u63d0\u4f9b\u6253\u5b57\u8212\u9069\u5ea6,\u624b\u8155\u652f\u6490\u5ea6\u589e\u52a0 54%;\u8207\u6c92\u6709\u624b\u638c\u652f\u6490\u7684\u6a19\u6e96\u9375\u76e4\u76f8\u6bd4,\u624b\u8155\u5f4e\u66f2\u6e1b\u5c11 25%<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u5b8c\u7f8e\u7684\u884c\u7a0b\u9375:\u8200\u51fa\u7684\u6309\u9375\u8207\u6307\u5c16\u5f62\u72c0\u76f8\u5339\u914d,\u56e0\u6b64\u60a8\u53ef\u4ee5\u653e\u5fc3\u5730\u4f7f\u7528\u5c08\u70ba\u8212\u9069\u3001\u7cbe\u78ba\u548c\u6d41\u52d5\u6027\u7684\u7121\u7dda\u9375\u76e4\u9032\u884c\u6253\u5b57\u3002<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u53ef\u8abf\u5f0f\u624b\u638c\u5347\u964d:\u7121\u8ad6\u5750\u8457\u9084\u662f\u7ad9\u8457,\u7b26\u5408\u4eba\u9ad4\u5de5\u5b78\u8a2d\u8a08\u7684\u50be\u659c\u817f\u70ba 0\u3001-4 \u548c -7 \u5ea6,\u8b93\u60a8\u7684\u624b\u8155\u4fdd\u6301\u5b8c\u5168\u8212\u9069,\u4e26\u4fdd\u6301\u81ea\u7136\u7684\u6253\u5b57\u59ff\u52e2\u3002<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u4eba\u9ad4\u5de5\u5b78\u5e2b\u8a8d\u8b49:ERGO K860 \u7121\u7dda\u4eba\u9ad4\u5de5\u5b78\u9375\u76e4\u7d93\u7f8e\u570b\u4eba\u9ad4\u5de5\u5b78\u8a8d\u8b49,\u53ef\u6539\u5584\u59ff\u52e2\u548c\u964d\u4f4e\u808c\u8089\u75b2\u52de\u3002<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u719f\u6089\u7684\u529f\u80fd:\u65b9\u4fbf\u5730\u9023\u63a5 USB \u63a5\u6536\u5668\u6216\u85cd\u7259,\u81ea\u5b9a\u7fa9 Fn \u9375\u7684\u4f7f\u7528,\u4e26\u4eab\u53d7\u5b89\u975c\u7684\u6309\u9375,\u5168\u5c3a\u5bf8\u4f48\u5c40\u548c CAPS LOCK \u6307\u793a\u5668\u3002<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<table class=\"a-normal a-spacing-micro\">\n<tbody>\n<tr class=\"a-spacing-small po-brand\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u54c1\u724c<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">Logitech<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-compatible_devices\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u76f8\u5bb9\u88dd\u7f6e<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">\u76f8\u5bb9\u65bc Windows\u3001macOS\u3001Linux \u548c Chrome OS<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-connectivity_technology\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u9023\u7dda\u6280\u8853<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">\u85cd\u7259<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-keyboard_description\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u9375\u76e4\u63cf\u8ff0<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">Qwerty<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-recommended_uses_for_product\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u7522\u54c1\u63a8\u85a6\u7528\u9014<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">\u65e5\u5e38\u4f7f\u7528<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-special_feature\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u7279\u6b8a\u529f\u80fd<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">\u53ef\u81ea\u8a02\u986f\u793a\u9375, \u8155\u6258, \u4eba\u9ad4\u5de5\u5b78, \u53ef\u81ea\u8a02\u6309\u9375\u5716\u6848, \u9632\u6c61, \u8b77\u8155<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-color\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u984f\u8272<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">\u9ed1\u8272<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"featured_media":1405,"template":"","meta":[],"product_cat":[37],"product_tag":[],"_links":{"self":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product\/1404"}],"collection":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/media\/1405"}],"wp:attachment":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/media?parent=1404"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=1404"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=1404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}