{"id":1297,"date":"2024-11-20T14:57:26","date_gmt":"2024-11-20T06:57:26","guid":{"rendered":"https:\/\/www.tai-marketing.com\/?post_type=product&#038;p=1297"},"modified":"2024-11-20T14:57:26","modified_gmt":"2024-11-20T06:57:26","slug":"dewenwils-outdoor-extension-cord","status":"publish","type":"product","link":"https:\/\/www.tai-marketing.com\/index.php\/product\/dewenwils-outdoor-extension-cord\/","title":{"rendered":"DEWENWILS Outdoor Extension Cord"},"content":{"rendered":"<p>\u3010 1 \u81f3 3 \u5206\u7dda\u5668 \u3011 \u7e3d\u9577\u5ea6 40 \u82f1\u5c3a\uff0822\u2019+6\u2019+6\u2019+6\u2019\uff09\uff1b\u5c07 1 \u500b\u7246\u58c1\u63d2\u5ea7\u64f4\u5c55\u70ba 3 \u500b\u64f4\u5c55\u63d2\u5ea7\uff08\u5f9e\u4e00\u7aef\u5230\u53e6\u4e00\u7aef\u9577\u9054 28 \u82f1\u5c3a\uff09\uff1b\u7da0\u8272\u4e09\u8def\u96fb\u6e90\u7dda\u5206\u914d\u5668\u6709\u52a9\u65bc\u4f7f\u7528\u66f4\u5c11\u7684\u96fb\u7dda\u8f15\u9b06\u8a2d\u7f6e\u666f\u89c0\u7167\u660e\u548c\u8056\u8a95\u88dd\u98fe<br \/>\n\u3010 16\/3C \u898f\u683c\u7dda \u3011 AC 125V\uff0c13A\uff0c\u984d\u5b9a\u529f\u7387 1625W\uff1b\u63a1\u7528\u5168\u9285\u7dda\u3001\u52a0\u56fa\u5200\u7247\u548c\u96d9\u8b77\u5957\u7dda\u88fd\u6210\uff1b 16 AWG \u91cd\u578b\u96fb\u7e9c\u53ef\u8b93\u60a8\u540c\u6642\u70ba\u591a\u500b\u8a2d\u5099\u4f9b\u96fb<br \/>\n\u3010SJTW\u9632\u98a8\u96e8\u7dda\u3011\u63a1\u7528\u8010\u78e8PVC\u5916\u8b77\u5957\uff0c\u63a1\u7528\u5168\u6210\u578b\u8a2d\u8a08\uff0c\u53ef\u627f\u53d7\u7d42\u8eab\u78e8\u640d\uff1b\u9019\u6b3e\u6236\u5916\u5ef6\u9577\u7dda\u975e\u5e38\u5805\u97cc\uff0c\u53ef\u4ee5\u62b5\u6297\u78e8\u640d\u3001\u6f6e\u6fd5\u548c\u967d\u5149\u76f4\u5c04<br \/>\n\u3010\u5b89\u5168\u63d2\u5ea7\u84cb\u30113\u500b\u63a5\u5730\u63d2\u5ea7\u5ef6\u9577\u7dda\u9069\u5408\u5728\u6f6e\u6fd5\u7684\u5730\u65b9\u4f7f\u7528\uff1b\u6bcf\u500b\u63d2\u5ea7\u63d2\u982d\u5747\u914d\u6709\u5b89\u5168\u84cb\uff0c\u53ef\u9632\u6b62\u96e8\u3001\u96ea\u548c\u7070\u5875<\/p>\n","protected":false},"excerpt":{"rendered":"<table class=\"a-normal a-spacing-micro\">\n<tbody>\n<tr class=\"a-spacing-small po-color\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u984f\u8272<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">Green<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-brand\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u54c1\u724c<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">DEWENWILS<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-connector_gender\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u9023\u63a5\u5668\u6027\u5225<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">Male-to-Female<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-voltage\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u96fb\u58d3<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">125 Volts<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-input_current\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u8f38\u5165\u96fb\u6d41<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">13 Amps<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"featured_media":1298,"template":"","meta":[],"product_cat":[35],"product_tag":[],"_links":{"self":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product\/1297"}],"collection":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/media\/1298"}],"wp:attachment":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/media?parent=1297"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=1297"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=1297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}