{"id":1284,"date":"2024-11-20T13:52:32","date_gmt":"2024-11-20T05:52:32","guid":{"rendered":"https:\/\/www.tai-marketing.com\/?post_type=product&#038;p=1284"},"modified":"2024-11-20T13:52:32","modified_gmt":"2024-11-20T05:52:32","slug":"woods16-3-sjtw","status":"publish","type":"product","link":"https:\/\/www.tai-marketing.com\/index.php\/product\/woods16-3-sjtw\/","title":{"rendered":"Woods16\/3 SJTW \u4e00\u822c\u7528\u9014\u5ef6\u9577\u7dda"},"content":{"rendered":"<ul class=\"a-unordered-list a-vertical a-spacing-mini\">\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u6236\u5916\u5ef6\u9577\u7dda;\u975e\u5e38\u9069\u5408\u5712\u6797\u7da0\u5316;\u4ee5\u53ca\u70ba\u5546\u5e97\u4f11\u5047\u7b49\u5bb6\u96fb\u4f9b\u96fb;\u96dc\u8349\u7de8;\u704c\u6728\u4fee\u526a\u6a5f;\u5439\u8449\u6a5f\u548c\u96fb\u52d5\u5272\u8349\u6a5f<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u91cd\u578b 16 \u6e2c\u91cf;3 \u500b\u7ba1\u9f4a;10 \u82f1\u5c3a(\u7d04 30.5 \u516c\u5c3a)\u5ef6\u9577\u7dda\u63d0\u4f9b<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u9ad8\u5ea6\u53ef\u898b\u7684\u6a59\u8272\u593e\u514b\u63d0\u4f9b\u984d\u5916\u7684\u5b89\u5168,\u9632\u6b62\u5728\u9662\u5b50\u88e1\u5de5\u4f5c\u6642\u7d46\u5012<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u9632\u6c34\u5f48\u6027\u4e59\u70ef\u57fa\u5916\u5957\u53ef\u4fdd\u8b77\u96fb\u7dda\u514d\u53d7\u6fd5\u6c23\u3001\u78e8\u640d\u548c\u967d\u5149\u7167\u5c04<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u8010\u7528\u7684\u9632\u6c34\u6a21\u88fd\u63d2\u982d;\u63d2\u5ea7\u548c\u52a0\u56fa\u5200\u7247\u53ef\u9632\u6b62\u610f\u5916\u5f4e\u66f2\u6216\u65b7\u88c2,\u4ee5\u78ba\u4fdd\u59cb\u7d42\u5b89\u5168 10 AMP;125 \u4f0f\u7279\u548c 1250 \u74e6<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<table class=\"a-normal a-spacing-micro\">\n<tbody>\n<tr class=\"a-spacing-small po-color\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u984f\u8272<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">\u6a58\u8272<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-brand\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u54c1\u724c<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">Woods<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-connector_gender\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u9023\u63a5\u5668\u6027\u5225<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">\u6bcd\u5934\u8f6c\u516c\u5934<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-voltage\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u96fb\u58d3<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">125 Volts<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-input_current\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u8f38\u5165\u96fb\u6d41<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">13 Amps<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"featured_media":1285,"template":"","meta":[],"product_cat":[35],"product_tag":[],"_links":{"self":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product\/1284"}],"collection":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/media\/1285"}],"wp:attachment":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/media?parent=1284"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=1284"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=1284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}