{"id":1274,"date":"2024-11-20T13:47:31","date_gmt":"2024-11-20T05:47:31","guid":{"rendered":"https:\/\/www.tai-marketing.com\/?post_type=product&#038;p=1274"},"modified":"2024-11-20T13:47:31","modified_gmt":"2024-11-20T05:47:31","slug":"amazon-basics-power-extension-cord-25-feet","status":"publish","type":"product","link":"https:\/\/www.tai-marketing.com\/index.php\/product\/amazon-basics-power-extension-cord-25-feet\/","title":{"rendered":"Amazon Basics \u96fb\u6e90\u5ef6\u9577\u7dda 25 \u82f1\u5c3a"},"content":{"rendered":"<ul class=\"a-unordered-list a-vertical a-spacing-mini\">\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u5305\u542b:25 \u82f1\u5c3a(\u7d04 7.6 \u516c\u5c3a)\u9ed1\u8272\u5ef6\u9577\u7dda;\u5728\u9700\u8981\u6642\u975e\u5e38\u9069\u5408\u5ef6\u9577\u96fb\u6e90<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u88dd\u7f6e\u76f8\u5bb9\u6027:13 \u5b89\u57f9\/125V \u96fb\u6e90;16 AWG<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u591a\u529f\u80fd:\u5728\u5ba4\u5167\u4f7f\u7528\u6d88\u8cbb\u96fb\u5b50\u7522\u54c1\u3001\u5de5\u5177\u3001\u5a92\u9ad4\u8a2d\u5099\u7b49<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u6613\u65bc\u4f7f\u7528:\u63d2\u5165\u4efb\u4f55\u6a19\u6e96 3 \u8173\u96fb\u6e90\u63d2\u5ea7;\u53ef\u63a5\u53d7 2 \u6216 3 \u8173\u88dd\u7f6e\u63d2\u982d<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<table class=\"a-normal a-spacing-micro\">\n<tbody>\n<tr class=\"a-spacing-small po-color\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u984f\u8272<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">\u9ed1\u8272<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-brand\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u54c1\u724c<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">Amazon Basics<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-connector_gender\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u9023\u63a5\u5668\u6027\u5225<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">\u6bcd\u5934\u8f6c\u516c\u5934<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-voltage\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u96fb\u58d3<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">125 Volts<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-input_current\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u8f38\u5165\u96fb\u6d41<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">13 Amps<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"featured_media":1275,"template":"","meta":[],"product_cat":[35],"product_tag":[],"_links":{"self":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product\/1274"}],"collection":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/media\/1275"}],"wp:attachment":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/media?parent=1274"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=1274"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=1274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}