{"id":1140,"date":"2024-11-18T20:13:45","date_gmt":"2024-11-18T12:13:45","guid":{"rendered":"https:\/\/www.tai-marketing.com\/?post_type=product&#038;p=1140"},"modified":"2024-11-18T20:13:45","modified_gmt":"2024-11-18T12:13:45","slug":"sansui-24-ips","status":"publish","type":"product","link":"https:\/\/www.tai-marketing.com\/index.php\/product\/sansui-24-ips\/","title":{"rendered":"SANSUI \u96fb\u8166\u986f\u793a\u5668 24 \u540b IPS"},"content":{"rendered":"<ul class=\"a-unordered-list a-vertical a-spacing-mini\">\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\ud83c\udf08 24 \u540b IPS \u773c\u90e8\u8b77\u7406 VESA \u986f\u793a\u5668,\u9069\u7528\u65bc\u5bb6\u5ead\u3001\u904a\u6232\u548c\u8fa6\u516c\u5ba4<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u26a1\u5237\u65b0\u7387:60Hz\/75Hz(\u9ad8\u9054 75Hz);\u89e3\u6790\u5ea6:1920*1080(FHD);\u4eae\u5ea6:250 \u5c3c\u7279;FreeSync \u6280\u8853<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u63a5\u53e3:HDMI 1.4 \u548c VGA \u7aef\u53e3(\u5305\u62ec HDMI \u7dda);\u7121\u63da\u8072\u5668\u548c\u8033\u6a5f\u63d2\u5b54\u3002 \u6709\u7dda\u9023\u63a5<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\ufe0f\u4eba\u9ad4\u5de5\u5b78\u8a2d\u8a08:\u6613\u65bc\u5b89\u88dd\u7684\u7a69\u5b9a\u652f\u67b6,-5\u00b0~22\u00b0\u50be\u659c,178\u00b0V\/H\u8996\u89d2,75\u00d775mm VESA \u76f8\u5bb9<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u4fdd\u56fa:SANSUI 24 \u540b\u986f\u793a\u5668\u63d0\u4f9b 30 \u5929\u9000\u6b3e\u4fdd\u8b49,\u5f9e\u8a02\u55ae\u65e5\u671f\u8d77\u514d\u8cbb\u66f4\u63db\u4fdd\u56fa\u548c\u7d42\u8eab\u6280\u8853\u652f\u63f4\u3002<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<table class=\"a-normal a-spacing-micro\">\n<tbody>\n<tr class=\"a-spacing-small po-brand\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u54c1\u724c<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">SANSUI<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-display.size\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u87a2\u5e55\u5c3a\u5bf8<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">23.8 Inches<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-resolution\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u89e3\u6790\u5ea6<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">FHD 1080p<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-aspect_ratio\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u9577\u5bec\u6bd4<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">16:9<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-screen_surface_description\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">\u87a2\u5e55\u8868\u9762\u63cf\u8ff0<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">\u9727\u9762<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"featured_media":1141,"template":"","meta":[],"product_cat":[33],"product_tag":[],"_links":{"self":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product\/1140"}],"collection":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/media\/1141"}],"wp:attachment":[{"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/media?parent=1140"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=1140"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.tai-marketing.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=1140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}